{"id":196113,"date":"2026-07-23T15:21:21","date_gmt":"2026-07-23T13:21:21","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/"},"modified":"2026-07-23T15:21:21","modified_gmt":"2026-07-23T13:21:21","slug":"le-salaire-seul-ne-fidelise-pas-les-talents","status":"publish","type":"factorial_video","link":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/","title":{"rendered":"Le salaire seul ne fid\u00e9lise pas les talents"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_video_type":"highlight","_related_series":192403,"_related_episode":196089,"_related_season":0,"_video_source":"vimeo","_youtube_video_id":"","_vimeo_video_id":"1211769654","_speaker_id":196088,"_video_description":"Dans cette vid\u00e9o, Isabel Aranda et Carla Ripa explorent pourquoi l'argent ne suffit plus \u00e0 retenir les employ\u00e9s, soulignant l'importance des liens et de la culture d'entreprise. Elles mettent en avant que le leadership et la gestion d'\u00e9quipe doivent int\u00e9grer des valeurs claires et une communication efficace pour favoriser un environnement o\u00f9 les employ\u00e9s se sentent valoris\u00e9s et int\u00e9gr\u00e9s. La n\u00e9cessit\u00e9 d'un plan de carri\u00e8re align\u00e9 avec les aspirations personnelles est \u00e9galement abord\u00e9e, refl\u00e9tant un changement dans la perception du travail au sein des g\u00e9n\u00e9rations modernes. Selon Isabel Aranda et Carla Ripa, \u00e9tablir des relations solides au sein de l'entreprise est essentiel pour garantir la loyaut\u00e9. D\u00e9couvrez plus d'id\u00e9es et d'aper\u00e7us sur le sujet dans l'\u00e9pisode complet.","_video_transcription":"00:08 - Question 3 : Pourquoi l'argent ne suffit-il plus \u00e0 retenir qui que ce soit ?\n00:12 - A) Le salaire ne suffit pas.B) Les r\u00e8gles ont chang\u00e9.\n00:16 - C) Sans lien, il n'y a pas de loyaut\u00e9.D) Le joker.\n00:19 - Je choisis le joker car toutes les options propos\u00e9es sont r\u00e9elles et expliquent Je comprends un peu ce qui se passe. Donc, le Joker.\n00:27 - Dans ce cas, j'h\u00e9site surtout entre A et C.Je pense donc que je vais opter pour la C : sans lien, il n'y a pas de loyaut\u00e9.\n00:37 - Pour moi, les trois ont du sens.J'h\u00e9sitais entre A et C, mais j'ai finalement choisi C car j'ai l'impression que la lettre A englobe d\u00e9j\u00e0 beaucoup de choses,car le salaire ne suffit pas.\n00:46 - Et aujourd'hui, comme il y a beaucoup plus de choses qui prennent de plus en plus d'importance importance, comme ce dont nous avons d\u00e9j\u00e0 parl\u00e9 concernant la croissance, le progr\u00e8s,des avantages, de la flexibilit\u00e9, ainsi que de bien d'autres aspects qui entrent en ligne de compte dans le cadre m\u00eame de l'id\u00e9e selon laquelle le salaire ne suffit pas.\n00:59 - Et l\u00e0, je me suis dit que le C signifiait bien que sans lien, il n'y a pas de loyaut\u00e9,Cela m'a beaucoup fait r\u00e9fl\u00e9chir \u00e0 la culture d'entreprise.\n01:07 - Et je trouve que c'est un sujet tr\u00e8s important et, en r\u00e9alit\u00e9,Quand j'ai commenc\u00e9 chez Factorial, j'ai commenc\u00e9 par m'occuper de la culture, au sein du service culturel.\n01:14 - Et c'est l'une des choses que j'appr\u00e9cie le plus, en fait.\n01:19 - J'adore aussi le d\u00e9veloppement, mais, au fond, c'est l'une des choses Cela me r\u00e9jouit beaucoup, car je pense qu'il est tr\u00e8s, tr\u00e8s important que ton objectif dans la vie soit \u00e9troitement li\u00e9 au projet de l'entreprise lui-m\u00eame,comme s'il y avait une certaine coh\u00e9rence entre le projet que j'ai l'entreprise et ta raison d'\u00eatre.\n01:36 - Je trouve qu'il est tr\u00e8s important de trouver sa place et de se sentir int\u00e9gr\u00e9,sans compter, bien s\u00fbr, le fait d'avoir le sentiment que ce que tu fais D'accord, et c'est toi qui fais bouger les choses, tu fais partie d'un engrenage.\n01:48 - Je pense qu'il y a l\u00e0 de nombreux aspects qui sont tr\u00e8s importants.\n01:52 - Tout \u00e0 fait d'accord.En r\u00e9alit\u00e9, tout est important ici, vous avez d\u00e9j\u00e0 vu que j'ai toutes avec le Joker.\n01:59 - Mais bon, revenons aux principes de base.Comme vous pouvez le voir, j'aime bien faire des choses tr\u00e8s simples.\n02:06 - La pyramide de Maslow, et il nous disait : \u00ab Ce qui compte avant tout, ce sont les besoins \u00bb Pour survivre, j'ai besoin d'argent pour manger.\n02:13 - Et c'est vrai que j'ai besoin d'un salaire pour pouvoir Ou pas, mais bon,Disons simplement que j'ai besoin d'un revenu.\n02:20 - J'ai besoin d'un revenu pour pouvoir manger, comme le disait Cervantes,Quand on a faim, les sonnets ne viennent pas.\n02:27 - Il y a donc une sorte d'ordre.Mais en ce moment, il est tr\u00e8s important d'avoir une vision macrosociale.\n02:36 - Depuis la COVID, \u00e7a a \u00e9t\u00e9 un moment d\u00e9cisif o\u00f9 les gens il s'est rendu compte que la vie peut s'envoler en un instant et que devoir supporter un travail dans celui qui ne te convient pas, tu l'as \u00e0 faire en un minimum de temps.\n02:55 - Tout \u00e0 fait, ce n'est probablement pas un site pour toi.\n02:57 - Il y aura une place pour toi, c'est certain.Les r\u00e8gles ont donc chang\u00e9.\n03:02 - Aujourd'hui, le rapport des gens au travail est diff\u00e9rent.\n03:06 - Beaucoup de gens disent : \u00ab C'est que la g\u00e9n\u00e9ration Z est \u00bb \u00ab celle qui a chang\u00e9 la donne \u00bb.\n03:09 - Non, \u00e9coute, non.Les r\u00e8gles \u00e9voluent depuis de nombreuses ann\u00e9es.\n03:12 - C'est vrai, quand les mill\u00e9niaux sont arriv\u00e9s, je m'en souviens bien, j'entendais les responsables des ressources humaines : \u00ab Ouah ! \u00bb \u00ab Ces gens-l\u00e0, on n'y fait rien \u00bb. Bien s\u00fbr, chaque g\u00e9n\u00e9ration a d\u00e9j\u00e0 apport\u00e9 une \u00e9volution sociale, un changement, une am\u00e9lioration s'est produite,Jusqu'\u00e0 pr\u00e9sent, on constatait une am\u00e9lioration sociale.\n03:29 - Et cela signifiait que tu avais vu tes parents travailler d'une certaine mani\u00e8re En somme, tu cherchais sans cesse \u00e0 vivre mieux, \u00e0 mieux travailler.\n03:36 - Et cela a fait que le lien, l'id\u00e9e de : \u00ab quelle relation dois-je entretenir \u00ab Qu'en est-il de mon travail ? \u00bb ait chang\u00e9.\u00c0 l'heure actuelle, les gens travaillent juste assez pour pouvoir bien vivre,mais il ne vit pas pour travailler.\n03:50 - Autrefois, les gens vivaient pour travailler, car ils consid\u00e9raient que leur identit\u00e9 au niveau professionnel, certains sont encore l\u00e0,mais c'est ton identit\u00e9 professionnelle qui te donne de la valeur.\n04:01 - Pour ceux \u00e0 qui \u00e7a convient, tant mieux, on n'est pas tous au m\u00eame niveau.\n04:06 - Mais vous devez comprendre que l'identit\u00e9 professionnelle est li\u00e9e \u00e0 ce que tu fais, o\u00f9 tu le fais, \u00e0 quel moment tu le fais et dans quelle position tu le fais.\n04:16 - Pour beaucoup de gens, cette identit\u00e9 professionnelle est tout ce qui compte dans leur vie et que lorsqu'ils prennent leur retraite ou sont licenci\u00e9s, tout cela leur \u00e9chappe.\n04:25 - Tu me parles donc de ma raison d'\u00eatre, et le fait est que ma raison d'\u00eatre \u00e9tait rester dans cette entreprise et occuper ce poste.\n04:31 - Beaucoup de gens qui ne prennent pas leur retraite.\n04:32 - En effet, et beaucoup de gens ne supportent pas d'avoir quitt\u00e9 leur travail,qui ne le supporte pas parce que : \u00ab Quelle est mon identit\u00e9 maintenant ? \u00bb \u00ab Et maintenant, qui suis-je ? \u00bb Tu vois, il y a des gens, des entreprises tr\u00e8s int\u00e9ressantes,Je travaille actuellement sur un projet tr\u00e8s int\u00e9ressant avec des personnes de plus de 50 ans ans, parce que, bien s\u00fbr, ils commencent \u00e0 perdre le contact.\n04:51 - Et pourquoi commencent-ils \u00e0 perdre ce lien ?Car ils disent : \u00ab \u00c0 quoi bon, \u00e0 mon \u00e2ge ? \u00bb Alors, comment renouer ce lien ? Comment promouvoir cette id\u00e9e d'h\u00e9ritage ?\n04:59 - Comment mettre en valeur la vieillesse ?Il s'agit en effet de mesures que certaines entreprises prennent actuellement.\n05:05 - Le lien ne r\u00e9side donc pas seulement dans le fait que tu restes dans une entreprise,c'est quand tu es dans l'entreprise, ce que tu apportes \u00e0 l'entreprise,quelles valeurs tu apportes \u00e0 l'entreprise.\n05:16 - Les filles, merci beaucoup d'avoir partag\u00e9 votre exp\u00e9rience,Cela a \u00e9t\u00e9 une exp\u00e9rience tr\u00e8s enrichissante.\n05:20 - Le d\u00e9bat est termin\u00e9, merci beaucoup.Eh bien, merci \u00e0 toi, merci \u00e0 Factorial.\n05:25 - Nous nous sommes d\u00e9j\u00e0 crois\u00e9es \u00e0 plusieurs reprises, mais nous n'avons pas eu l'occasion de filer\u2026 De faire un \u00e0.\n05:30 - De pr\u00e9senter nos id\u00e9es de cette mani\u00e8re.Concr\u00e9tiser nos id\u00e9es.\n05:33 - Alors, quand tu veux, on se reverra.Super. C'est d\u00e9j\u00e0 r\u00e9gl\u00e9.\n05:38 - Tout \u00e0 fait. C'est parti.","_has_trailer":false,"_trailer_vimeo_id":"","_trailer_youtube_id":"","_video_duration":"","_video_thumbnail":""},"categories":[964,966],"factorial-categories":[],"class_list":["post-196113","factorial_video","type-factorial_video","status-publish","hentry","category-cles-du-leadership","category-developper-les-talents"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le salaire seul ne fid\u00e9lise pas les talents | Factorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le salaire seul ne fid\u00e9lise pas les talents\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorial.fr\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/\",\"url\":\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/\",\"name\":\"Le salaire seul ne fid\u00e9lise pas les talents | Factorial\",\"isPartOf\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#website\"},\"datePublished\":\"2026-07-23T13:21:21+00:00\",\"dateModified\":\"2026-07-23T13:21:21+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorial.fr\/blog\/#website\",\"url\":\"https:\/\/factorial.fr\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorial.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorial.fr\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorial.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le salaire seul ne fid\u00e9lise pas les talents | Factorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/","og_locale":"fr_FR","og_type":"article","og_title":"Le salaire seul ne fid\u00e9lise pas les talents","og_url":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","og_image":[{"width":1200,"height":628,"url":"https:\/\/factorial.fr\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@factorialapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/","url":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/","name":"Le salaire seul ne fid\u00e9lise pas les talents | Factorial","isPartOf":{"@id":"https:\/\/factorial.fr\/blog\/#website"},"datePublished":"2026-07-23T13:21:21+00:00","dateModified":"2026-07-23T13:21:21+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorial.fr\/blog\/factorial-play\/videos\/le-salaire-seul-ne-fidelise-pas-les-talents\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorial.fr\/blog\/#website","url":"https:\/\/factorial.fr\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorial.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorial.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/factorial.fr\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorial.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]}]}},"_links":{"self":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-videos\/196113"}],"collection":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-videos"}],"about":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/types\/factorial_video"}],"wp:attachment":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/media?parent=196113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/categories?post=196113"},{"taxonomy":"factorial_category","embeddable":true,"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-categories?post=196113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}