{"id":196092,"date":"2026-07-23T15:20:58","date_gmt":"2026-07-23T13:20:58","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/"},"modified":"2026-07-23T15:20:58","modified_gmt":"2026-07-23T13:20:58","slug":"on-the-deck-avantages-au-dela-du-salaire","status":"publish","type":"factorial_video","link":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/","title":{"rendered":"On The Deck | Avantages : au-del\u00e0 du salaire"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_video_type":"episode","_related_series":192403,"_related_episode":0,"_related_season":192730,"_video_source":"vimeo","_youtube_video_id":"","_vimeo_video_id":"1211769648","_speaker_id":196080,"_video_description":"Comment les entreprises peuvent-elles repenser leur culture et leur fa\u00e7on de travailler afin de garantir le bien-\u00eatre r\u00e9el de leurs employ\u00e9s ?\r\nDans cet \u00e9pisode, Isabel Aranda, docteure en psychologie et Wellbeing Manager chez Therapyside, et Carla Ripa, Head of Talent Development chez Factorial, analysent le bien-\u00eatre au travail et son impact sur la culture d\u2019entreprise et la r\u00e9tention des talents.\r\nAu cours de la conversation, les expertes d\u00e9battent de la mani\u00e8re d\u2019am\u00e9liorer le quotidien des employ\u00e9s gr\u00e2ce \u00e0 une structuration ad\u00e9quate du travail et pas seulement par des avantages superficiels.","_video_transcription":"","_has_trailer":false,"_trailer_vimeo_id":"","_trailer_youtube_id":"","_video_duration":"","_video_thumbnail":""},"categories":[],"factorial-categories":[],"class_list":["post-196092","factorial_video","type-factorial_video","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>On The Deck | Avantages : au-del\u00e0 du salaire | Factorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"On The Deck | Avantages : au-del\u00e0 du salaire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorial.fr\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/\",\"url\":\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/\",\"name\":\"On The Deck | Avantages : au-del\u00e0 du salaire | Factorial\",\"isPartOf\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#website\"},\"datePublished\":\"2026-07-23T13:20:58+00:00\",\"dateModified\":\"2026-07-23T13:20:58+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorial.fr\/blog\/#website\",\"url\":\"https:\/\/factorial.fr\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorial.fr\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorial.fr\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorial.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"On The Deck | Avantages : au-del\u00e0 du salaire | Factorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/","og_locale":"fr_FR","og_type":"article","og_title":"On The Deck | Avantages : au-del\u00e0 du salaire","og_url":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","og_image":[{"width":1200,"height":628,"url":"https:\/\/factorial.fr\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@factorialapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/","url":"https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/","name":"On The Deck | Avantages : au-del\u00e0 du salaire | Factorial","isPartOf":{"@id":"https:\/\/factorial.fr\/blog\/#website"},"datePublished":"2026-07-23T13:20:58+00:00","dateModified":"2026-07-23T13:20:58+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorial.fr\/blog\/factorial-play\/videos\/on-the-deck-avantages-au-dela-du-salaire\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorial.fr\/blog\/#website","url":"https:\/\/factorial.fr\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorial.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorial.fr\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/factorial.fr\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorial.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorial.fr\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorial.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]}]}},"_links":{"self":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-videos\/196092"}],"collection":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-videos"}],"about":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/types\/factorial_video"}],"wp:attachment":[{"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/media?parent=196092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/categories?post=196092"},{"taxonomy":"factorial_category","embeddable":true,"href":"https:\/\/factorial.fr\/blog\/wp-json\/wp\/v2\/factorial-categories?post=196092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}